{"id":12384,"date":"2023-05-29T13:04:00","date_gmt":"2023-05-29T06:04:00","guid":{"rendered":"https:\/\/areeya.co.th\/news-events\/%e0%b8%ad%e0%b8%b2%e0%b8%a3%e0%b8%b5%e0%b8%a2%e0%b8%b2-%e0%b8%9e%e0%b8%a3%e0%b8%ad%e0%b8%9e%e0%b9%80%e0%b8%9e%e0%b8%ad%e0%b8%a3%e0%b9%8c%e0%b8%95%e0%b8%b5%e0%b9%89-x-%e0%b8%9b%e0%b9%8a%e0%b8%ad\/"},"modified":"2023-05-29T13:05:03","modified_gmt":"2023-05-29T06:05:03","slug":"%e0%b8%ad%e0%b8%b2%e0%b8%a3%e0%b8%b5%e0%b8%a2%e0%b8%b2-%e0%b8%9e%e0%b8%a3%e0%b8%ad%e0%b8%9e%e0%b9%80%e0%b8%9e%e0%b8%ad%e0%b8%a3%e0%b9%8c%e0%b8%95%e0%b8%b5%e0%b9%89-x-%e0%b8%9b%e0%b9%8a%e0%b8%ad","status":"publish","type":"news-events","link":"https:\/\/areeya.co.th\/en\/news-events\/%E0%B8%AD%E0%B8%B2%E0%B8%A3%E0%B8%B5%E0%B8%A2%E0%B8%B2-%E0%B8%9E%E0%B8%A3%E0%B8%AD%E0%B8%9E%E0%B9%80%E0%B8%9E%E0%B8%AD%E0%B8%A3%E0%B9%8C%E0%B8%95%E0%B8%B5%E0%B9%89-x-%E0%B8%9B%E0%B9%8A%E0%B8%AD\/","title":{"rendered":"\u0e2d\u0e32\u0e23\u0e35\u0e22\u0e32 \u0e1e\u0e23\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 x \u0e1b\u0e4a\u0e2d\u0e04\u0e42\u0e04 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e2d\u0e31\u0e14\u0e42\u0e1b\u0e23\u0e2f \u0e41\u0e23\u0e07 \u201cCOLORS FREEVERRR\u201d \u0e0b\u0e37\u0e49\u0e2d\u0e1a\u0e49\u0e32\u0e19\u0e41\u0e16\u0e21\u0e23\u0e16"},"content":{"rendered":"<h1><strong>\u0e2d\u0e32\u0e23\u0e35\u0e22\u0e32 \u0e1e\u0e23\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 x \u0e1b\u0e4a\u0e2d\u0e04\u0e42\u0e04 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) <\/strong><\/h1>\n<h1><strong>\u0e2d\u0e31\u0e14\u0e42\u0e1b\u0e23\u0e2f \u0e41\u0e23\u0e07 \u201cCOLORS FREEVERRR\u201d \u0e0b\u0e37\u0e49\u0e2d\u0e1a\u0e49\u0e32\u0e19\u0e41\u0e16\u0e21\u0e23\u0e16<\/strong><\/h1>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-12380\" src=\"https:\/\/areeya.co.th\/wp-content\/uploads\/2023\/05\/c1-118.jpg\" alt=\"\" width=\"2508\" height=\"1672\" srcset=\"https:\/\/areeya.co.th\/wp-content\/uploads\/2023\/05\/c1-118.jpg 2508w, https:\/\/areeya.co.th\/wp-content\/uploads\/2023\/05\/c1-118-300x200.jpg 300w, https:\/\/areeya.co.th\/wp-content\/uploads\/2023\/05\/c1-118-1024x683.jpg 1024w, https:\/\/areeya.co.th\/wp-content\/uploads\/2023\/05\/c1-118-768x512.jpg 768w, https:\/\/areeya.co.th\/wp-content\/uploads\/2023\/05\/c1-118-1536x1024.jpg 1536w, https:\/\/areeya.co.th\/wp-content\/uploads\/2023\/05\/c1-118-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 2508px) 100vw, 2508px\" \/><\/p>\n<p><strong>\u0e2d\u0e32\u0e23\u0e35\u0e22\u0e32\u00a0\u0e1e\u0e23\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 <\/strong>\u0e1c\u0e39\u0e49\u0e19\u0e33\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e17\u0e35\u0e48\u0e15\u0e2d\u0e1a\u0e42\u0e08\u0e17\u0e22\u0e4c\u0e44\u0e25\u0e1f\u0e4c\u0e2a\u0e44\u0e15\u0e25\u0e4c\u0e17\u0e35\u0e48\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e04\u0e19 (Lifestyle Property Developer) \u0e42\u0e14\u0e22 <strong>\u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e1e\u0e31\u0e17\u0e18\u0e21\u0e25 \u0e40\u0e25\u0e32\u0e2b\u0e1e\u0e39\u0e19\u0e23\u0e31\u0e07\u0e29\u0e35<\/strong>\u00a0\u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e2d\u0e32\u0e27\u0e38\u0e42\u0e2a \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u00a0\u0e2d\u0e32\u0e23\u0e35\u0e22\u0e32\u00a0\u0e1e\u0e23\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\u00a0(\u0e21\u0e2b\u0e32\u0e0a\u0e19)<strong>\u00a0\u0e08\u0e31\u0e1a\u0e21\u0e37\u0e2d \u0e1b\u0e4a\u0e2d\u0e04\u0e42\u0e04 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c)<\/strong> \u0e42\u0e14\u0e22 BRG Group \u0e1c\u0e39\u0e49\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e02\u0e19\u0e32\u0e14\u0e40\u0e25\u0e47\u0e01 \u0e2a\u0e38\u0e14\u0e19\u0e48\u0e32\u0e23\u0e31\u0e01 \u0e40\u0e2b\u0e21\u0e32\u0e30\u0e01\u0e31\u0e1a\u0e44\u0e25\u0e1f\u0e4c\u0e2a\u0e44\u0e15\u0e25\u0e4c\u0e43\u0e19\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e42\u0e14\u0e22 <strong>\u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e2d\u0e31\u0e08\u0e08\u0e34\u0e21\u0e32 \u0e28\u0e23\u0e35\u0e23\u0e31\u0e15\u0e19\u0e1b\u0e23\u0e30\u0e20\u0e32\u0e2a<\/strong> \u0e41\u0e25\u0e30 <strong>\u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e0a\u0e25\u0e25\u0e18\u0e23 \u0e28\u0e23\u0e35\u0e23\u0e31\u0e15\u0e19\u0e1b\u0e23\u0e30\u0e20\u0e32\u0e2a <\/strong>\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e1b\u0e4a\u0e2d\u0e04\u0e42\u0e04 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14 <strong>\u0e21\u0e2d\u0e1a\u0e42\u0e1b\u0e23\u0e42\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e38\u0e14\u0e1e\u0e34\u0e40\u0e28\u0e29 \u0e17\u0e35\u0e48\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e40\u0e15\u0e34\u0e21\u0e40\u0e15\u0e47\u0e21\u0e2a\u0e35\u0e2a\u0e31\u0e19\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e04\u0e19\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e43\u0e19\u0e41\u0e04\u0e21\u0e40\u0e1b\u0e0d \u201cCOLORS FREEVERRR\u201d \u0e0b\u0e37\u0e49\u0e2d\u0e1a\u0e49\u0e32\u0e19\u0e41\u0e16\u0e21\u0e23\u0e16*<\/strong> \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e08\u0e2d\u0e07 \u0e41\u0e25\u0e30\u0e42\u0e2d\u0e19\u0e2f <a href=\"https:\/\/www.areeya.co.th\/townhome\/\" data-cke-saved-href=\"https:\/\/www.areeya.co.th\/townhome\/\"><strong>\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e40\u0e14\u0e2d\u0e30 \u0e04\u0e31\u0e25\u0e40\u0e25\u0e2d\u0e23\u0e4c\u0e2a <\/strong><\/a>\u0e17\u0e32\u0e27\u0e19\u0e4c\u0e42\u0e2e\u0e21\u0e43\u0e2b\u0e0d\u0e48 \u0e43\u0e2b\u0e49\u0e04\u0e38\u0e13\u0e43\u0e0a\u0e49\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e44\u0e14\u0e49\u0e40\u0e15\u0e47\u0e21\u0e17\u0e35\u0e48 \u0e1a\u0e19 4 \u0e17\u0e33\u0e40\u0e25\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e <a href=\"https:\/\/www.areeya.co.th\/townhome\/thecolors-bangna3\/\" data-cke-saved-href=\"https:\/\/www.areeya.co.th\/townhome\/thecolors-bangna3\/\">\u0e1a\u0e32\u0e07\u0e19\u0e32<\/a>, <a href=\"https:\/\/www.areeya.co.th\/townhome\/thecolors-rangsit\/\" data-cke-saved-href=\"https:\/\/www.areeya.co.th\/townhome\/thecolors-rangsit\/\">\u0e25\u0e33\u0e25\u0e39\u0e01\u0e01\u0e32-\u0e04\u0e25\u0e2d\u0e07 4<\/a>,<a href=\"https:\/\/www.areeya.co.th\/townhome\/thecolorspresale\/\" data-cke-saved-href=\"https:\/\/www.areeya.co.th\/townhome\/thecolorspresale\/\"> \u0e23\u0e32\u0e21\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e32-\u0e2b\u0e17\u0e31\u0e22\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c <\/a>\u0e41\u0e25\u0e30 <a href=\"https:\/\/www.areeya.co.th\/townhome\/thecolors-wongwaen-rachaphruk\/\" data-cke-saved-href=\"https:\/\/www.areeya.co.th\/townhome\/thecolors-wongwaen-rachaphruk\/\">\u0e27\u0e07\u0e41\u0e2b\u0e27\u0e19\u0e2f-\u0e23\u0e32\u0e0a\u0e1e\u0e24\u0e01\u0e29\u0e4c<\/a> \u0e43\u0e19<strong>\u0e23\u0e32\u0e04\u0e32\u0e1e\u0e34\u0e40\u0e28\u0e29\u0e2a\u0e38\u0e14\u0e40\u0e23\u0e34\u0e48\u0e21 1.89-3.88 \u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17 \u0e23\u0e31\u0e1a\u0e1f\u0e23\u0e35!! \u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 Pocco \u0e21\u0e39\u0e25\u0e04\u0e48\u0e32\u0e01\u0e27\u0e48\u0e32 420,000 \u0e1a\u0e32\u0e17 \u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e27\u0e31\u0e19\u0e19\u0e35\u0e49 &#8211; 30 \u0e1e\u0e24\u0e28\u0e08\u0e34\u0e01\u0e32\u0e22\u0e19 \u0e19\u0e35\u0e49\u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19<\/strong> (*\u0e40\u0e07\u0e37\u0e48\u0e2d\u0e19\u0e44\u0e02\u0e40\u0e1b\u0e47\u0e19\u0e44\u0e1b\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e2f \u0e01\u0e33\u0e2b\u0e19\u0e14)<\/p>\n<p>\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e17\u0e35\u0e48\u0e01\u0e33\u0e25\u0e31\u0e07\u0e21\u0e2d\u0e07\u0e2b\u0e32 \u0e17\u0e32\u0e27\u0e19\u0e4c\u0e42\u0e2e\u0e21\u0e2a\u0e44\u0e15\u0e25\u0e4c\u0e42\u0e21\u0e40\u0e14\u0e34\u0e23\u0e4c\u0e19\u0e17\u0e35\u0e48\u0e40\u0e15\u0e47\u0e21\u0e44\u0e1b\u0e14\u0e49\u0e27\u0e22<strong> \u201c\u0e2a\u0e35\u0e2a\u0e31\u0e19\u201d \u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e04\u0e2d\u0e19\u0e40\u0e0b\u0e1b\u0e15\u0e4c \u201cLive The Colorful Life\u201d<\/strong> \u0e1a\u0e19\u0e17\u0e33\u0e40\u0e25\u0e28\u0e31\u0e22\u0e20\u0e32\u0e1e \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e2a\u0e31\u0e07\u0e04\u0e21\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e<\/p>\n<p>\u0e25\u0e07\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19\u0e23\u0e31\u0e1a\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c\u0e01\u0e48\u0e2d\u0e19\u0e43\u0e04\u0e23 (\u0e08\u0e33\u0e19\u0e27\u0e19\u0e08\u0e33\u0e01\u0e31\u0e14) \u0e04\u0e25\u0e34\u0e01 <a href=\"https:\/\/bit.ly\/3QLMkpV\" data-cke-saved-href=\"https:\/\/bit.ly\/3QLMkpV\">https:\/\/bit.ly\/3QLMkpV<\/a><\/p>\n<p>\u0e2a\u0e2d\u0e1a\u0e16\u0e32\u0e21\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21 \u0e44\u0e14\u0e49\u0e17\u0e35\u0e48 <a href=\"http:\/\/www.areeya.co.th\" data-cke-saved-href=\"http:\/\/www.areeya.co.th\">www.areeya.co.th<\/a><\/p>\n<p>LINE\u00a0@areeyahome<\/p>\n<p>\u0e2b\u0e23\u0e37\u0e2d\u0e42\u0e17\u0e23.1797<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e2d\u0e32\u0e23\u0e35\u0e22\u0e32 \u0e1e\u0e23\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 x \u0e1b\u0e4a\u0e2d\u0e04\u0e42\u0e04 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e2d\u0e31\u0e14\u0e42\u0e1b\u0e23\u0e2f \u0e41\u0e23\u0e07 \u201cCOLORS FREEVERRR\u201d \u0e0b\u0e37\u0e49\u0e2d\u0e1a\u0e49\u0e32\u0e19\u0e41\u0e16\u0e21\u0e23\u0e16 \u0e2d\u0e32\u0e23\u0e35\u0e22\u0e32\u00a0\u0e1e\u0e23\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e1c\u0e39\u0e49\u0e19\u0e33\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e17\u0e35\u0e48\u0e15\u0e2d\u0e1a\u0e42\u0e08\u0e17\u0e22\u0e4c\u0e44\u0e25\u0e1f\u0e4c\u0e2a\u0e44\u0e15\u0e25\u0e4c\u0e17\u0e35\u0e48\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e04\u0e19 (Lifestyle Property Developer) \u0e42\u0e14\u0e22 \u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e1e\u0e31\u0e17\u0e18\u0e21\u0e25 \u0e40\u0e25\u0e32\u0e2b\u0e1e\u0e39\u0e19\u0e23\u0e31\u0e07\u0e29\u0e35\u00a0\u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e2d\u0e32\u0e27\u0e38\u0e42\u0e2a \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u00a0\u0e2d\u0e32\u0e23\u0e35\u0e22\u0e32\u00a0\u0e1e\u0e23\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\u00a0(\u0e21\u0e2b\u0e32\u0e0a\u0e19)\u00a0\u0e08\u0e31\u0e1a\u0e21\u0e37\u0e2d \u0e1b\u0e4a\u0e2d\u0e04\u0e42\u0e04 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e42\u0e14\u0e22 BRG Group \u0e1c\u0e39\u0e49\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e02\u0e19\u0e32\u0e14\u0e40\u0e25\u0e47\u0e01 \u0e2a\u0e38\u0e14\u0e19\u0e48\u0e32\u0e23\u0e31\u0e01 \u0e40\u0e2b\u0e21\u0e32\u0e30\u0e01\u0e31\u0e1a\u0e44\u0e25\u0e1f\u0e4c\u0e2a\u0e44\u0e15\u0e25\u0e4c\u0e43\u0e19\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e42\u0e14\u0e22 \u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e2d\u0e31\u0e08\u0e08\u0e34\u0e21\u0e32 \u0e28\u0e23\u0e35\u0e23\u0e31\u0e15\u0e19\u0e1b\u0e23\u0e30\u0e20\u0e32\u0e2a \u0e41\u0e25\u0e30 \u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e0a\u0e25\u0e25\u0e18\u0e23 \u0e28\u0e23\u0e35\u0e23\u0e31\u0e15\u0e19\u0e1b\u0e23\u0e30\u0e20\u0e32\u0e2a \u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e1b\u0e4a\u0e2d\u0e04\u0e42\u0e04 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14 \u0e21\u0e2d\u0e1a\u0e42\u0e1b\u0e23\u0e42\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e38\u0e14\u0e1e\u0e34\u0e40\u0e28\u0e29 \u0e17\u0e35\u0e48\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e40\u0e15\u0e34\u0e21\u0e40\u0e15\u0e47\u0e21\u0e2a\u0e35\u0e2a\u0e31\u0e19\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e04\u0e19\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e43\u0e19\u0e41\u0e04\u0e21\u0e40\u0e1b\u0e0d \u201cCOLORS FREEVERRR\u201d \u0e0b\u0e37\u0e49\u0e2d\u0e1a\u0e49\u0e32\u0e19\u0e41\u0e16\u0e21\u0e23\u0e16* \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e08\u0e2d\u0e07 \u0e41\u0e25\u0e30\u0e42\u0e2d\u0e19\u0e2f \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e40\u0e14\u0e2d\u0e30 \u0e04\u0e31\u0e25\u0e40\u0e25\u0e2d\u0e23\u0e4c\u0e2a \u0e17\u0e32\u0e27\u0e19\u0e4c\u0e42\u0e2e\u0e21\u0e43\u0e2b\u0e0d\u0e48 \u0e43\u0e2b\u0e49\u0e04\u0e38\u0e13\u0e43\u0e0a\u0e49\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e44\u0e14\u0e49\u0e40\u0e15\u0e47\u0e21\u0e17\u0e35\u0e48 \u0e1a\u0e19 4 \u0e17\u0e33\u0e40\u0e25\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e \u0e1a\u0e32\u0e07\u0e19\u0e32,&#8230;<\/p>\n","protected":false},"author":6,"featured_media":12373,"template":"","class_list":["post-12384","news-events","type-news-events","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Areeya joins hands with Pocco to launches \u201cCOLORS FREEVERRR&quot; | \u0e2d\u0e32\u0e23\u0e35\u0e22\u0e32 \u0e1e\u0e23\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/areeya.co.th\/en\/news-events\/\u0e2d\u0e32\u0e23\u0e35\u0e22\u0e32-\u0e1e\u0e23\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49-x-\u0e1b\u0e4a\u0e2d\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Areeya joins hands with Pocco to launches \u201cCOLORS FREEVERRR&quot; | \u0e2d\u0e32\u0e23\u0e35\u0e22\u0e32 \u0e1e\u0e23\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49\" \/>\n<meta property=\"og:description\" content=\"\u0e2d\u0e32\u0e23\u0e35\u0e22\u0e32 \u0e1e\u0e23\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 x \u0e1b\u0e4a\u0e2d\u0e04\u0e42\u0e04 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e2d\u0e31\u0e14\u0e42\u0e1b\u0e23\u0e2f \u0e41\u0e23\u0e07 \u201cCOLORS FREEVERRR\u201d \u0e0b\u0e37\u0e49\u0e2d\u0e1a\u0e49\u0e32\u0e19\u0e41\u0e16\u0e21\u0e23\u0e16 \u0e2d\u0e32\u0e23\u0e35\u0e22\u0e32\u00a0\u0e1e\u0e23\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e1c\u0e39\u0e49\u0e19\u0e33\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e17\u0e35\u0e48\u0e15\u0e2d\u0e1a\u0e42\u0e08\u0e17\u0e22\u0e4c\u0e44\u0e25\u0e1f\u0e4c\u0e2a\u0e44\u0e15\u0e25\u0e4c\u0e17\u0e35\u0e48\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e04\u0e19 (Lifestyle Property Developer) \u0e42\u0e14\u0e22 \u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e1e\u0e31\u0e17\u0e18\u0e21\u0e25 \u0e40\u0e25\u0e32\u0e2b\u0e1e\u0e39\u0e19\u0e23\u0e31\u0e07\u0e29\u0e35\u00a0\u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e2d\u0e32\u0e27\u0e38\u0e42\u0e2a \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u00a0\u0e2d\u0e32\u0e23\u0e35\u0e22\u0e32\u00a0\u0e1e\u0e23\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\u00a0(\u0e21\u0e2b\u0e32\u0e0a\u0e19)\u00a0\u0e08\u0e31\u0e1a\u0e21\u0e37\u0e2d \u0e1b\u0e4a\u0e2d\u0e04\u0e42\u0e04 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e42\u0e14\u0e22 BRG Group \u0e1c\u0e39\u0e49\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e02\u0e19\u0e32\u0e14\u0e40\u0e25\u0e47\u0e01 \u0e2a\u0e38\u0e14\u0e19\u0e48\u0e32\u0e23\u0e31\u0e01 \u0e40\u0e2b\u0e21\u0e32\u0e30\u0e01\u0e31\u0e1a\u0e44\u0e25\u0e1f\u0e4c\u0e2a\u0e44\u0e15\u0e25\u0e4c\u0e43\u0e19\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e42\u0e14\u0e22 \u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e2d\u0e31\u0e08\u0e08\u0e34\u0e21\u0e32 \u0e28\u0e23\u0e35\u0e23\u0e31\u0e15\u0e19\u0e1b\u0e23\u0e30\u0e20\u0e32\u0e2a \u0e41\u0e25\u0e30 \u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e0a\u0e25\u0e25\u0e18\u0e23 \u0e28\u0e23\u0e35\u0e23\u0e31\u0e15\u0e19\u0e1b\u0e23\u0e30\u0e20\u0e32\u0e2a \u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e1b\u0e4a\u0e2d\u0e04\u0e42\u0e04 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14 \u0e21\u0e2d\u0e1a\u0e42\u0e1b\u0e23\u0e42\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e38\u0e14\u0e1e\u0e34\u0e40\u0e28\u0e29 \u0e17\u0e35\u0e48\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e40\u0e15\u0e34\u0e21\u0e40\u0e15\u0e47\u0e21\u0e2a\u0e35\u0e2a\u0e31\u0e19\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e04\u0e19\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e43\u0e19\u0e41\u0e04\u0e21\u0e40\u0e1b\u0e0d \u201cCOLORS FREEVERRR\u201d \u0e0b\u0e37\u0e49\u0e2d\u0e1a\u0e49\u0e32\u0e19\u0e41\u0e16\u0e21\u0e23\u0e16* \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e08\u0e2d\u0e07 \u0e41\u0e25\u0e30\u0e42\u0e2d\u0e19\u0e2f \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e40\u0e14\u0e2d\u0e30 \u0e04\u0e31\u0e25\u0e40\u0e25\u0e2d\u0e23\u0e4c\u0e2a \u0e17\u0e32\u0e27\u0e19\u0e4c\u0e42\u0e2e\u0e21\u0e43\u0e2b\u0e0d\u0e48 \u0e43\u0e2b\u0e49\u0e04\u0e38\u0e13\u0e43\u0e0a\u0e49\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e44\u0e14\u0e49\u0e40\u0e15\u0e47\u0e21\u0e17\u0e35\u0e48 \u0e1a\u0e19 4 \u0e17\u0e33\u0e40\u0e25\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e \u0e1a\u0e32\u0e07\u0e19\u0e32,...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/areeya.co.th\/en\/news-events\/\u0e2d\u0e32\u0e23\u0e35\u0e22\u0e32-\u0e1e\u0e23\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49-x-\u0e1b\u0e4a\u0e2d\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0e2d\u0e32\u0e23\u0e35\u0e22\u0e32 \u0e1e\u0e23\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-29T06:05:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/areeya.co.th\/wp-content\/uploads\/2023\/05\/cover-d-81.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/areeya.co.th\\\/en\\\/news-events\\\/%E0%B8%AD%E0%B8%B2%E0%B8%A3%E0%B8%B5%E0%B8%A2%E0%B8%B2-%E0%B8%9E%E0%B8%A3%E0%B8%AD%E0%B8%9E%E0%B9%80%E0%B8%9E%E0%B8%AD%E0%B8%A3%E0%B9%8C%E0%B8%95%E0%B8%B5%E0%B9%89-x-%E0%B8%9B%E0%B9%8A%E0%B8%AD\\\/\",\"url\":\"https:\\\/\\\/areeya.co.th\\\/en\\\/news-events\\\/%E0%B8%AD%E0%B8%B2%E0%B8%A3%E0%B8%B5%E0%B8%A2%E0%B8%B2-%E0%B8%9E%E0%B8%A3%E0%B8%AD%E0%B8%9E%E0%B9%80%E0%B8%9E%E0%B8%AD%E0%B8%A3%E0%B9%8C%E0%B8%95%E0%B8%B5%E0%B9%89-x-%E0%B8%9B%E0%B9%8A%E0%B8%AD\\\/\",\"name\":\"Areeya joins hands with Pocco to launches \u201cCOLORS FREEVERRR\\\" | \u0e2d\u0e32\u0e23\u0e35\u0e22\u0e32 \u0e1e\u0e23\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/areeya.co.th\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/areeya.co.th\\\/en\\\/news-events\\\/%E0%B8%AD%E0%B8%B2%E0%B8%A3%E0%B8%B5%E0%B8%A2%E0%B8%B2-%E0%B8%9E%E0%B8%A3%E0%B8%AD%E0%B8%9E%E0%B9%80%E0%B8%9E%E0%B8%AD%E0%B8%A3%E0%B9%8C%E0%B8%95%E0%B8%B5%E0%B9%89-x-%E0%B8%9B%E0%B9%8A%E0%B8%AD\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/areeya.co.th\\\/en\\\/news-events\\\/%E0%B8%AD%E0%B8%B2%E0%B8%A3%E0%B8%B5%E0%B8%A2%E0%B8%B2-%E0%B8%9E%E0%B8%A3%E0%B8%AD%E0%B8%9E%E0%B9%80%E0%B8%9E%E0%B8%AD%E0%B8%A3%E0%B9%8C%E0%B8%95%E0%B8%B5%E0%B9%89-x-%E0%B8%9B%E0%B9%8A%E0%B8%AD\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/areeya.co.th\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/cover-d-81.jpg\",\"datePublished\":\"2023-05-29T06:04:00+00:00\",\"dateModified\":\"2023-05-29T06:05:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/areeya.co.th\\\/en\\\/news-events\\\/%E0%B8%AD%E0%B8%B2%E0%B8%A3%E0%B8%B5%E0%B8%A2%E0%B8%B2-%E0%B8%9E%E0%B8%A3%E0%B8%AD%E0%B8%9E%E0%B9%80%E0%B8%9E%E0%B8%AD%E0%B8%A3%E0%B9%8C%E0%B8%95%E0%B8%B5%E0%B9%89-x-%E0%B8%9B%E0%B9%8A%E0%B8%AD\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/areeya.co.th\\\/en\\\/news-events\\\/%E0%B8%AD%E0%B8%B2%E0%B8%A3%E0%B8%B5%E0%B8%A2%E0%B8%B2-%E0%B8%9E%E0%B8%A3%E0%B8%AD%E0%B8%9E%E0%B9%80%E0%B8%9E%E0%B8%AD%E0%B8%A3%E0%B9%8C%E0%B8%95%E0%B8%B5%E0%B9%89-x-%E0%B8%9B%E0%B9%8A%E0%B8%AD\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/areeya.co.th\\\/en\\\/news-events\\\/%E0%B8%AD%E0%B8%B2%E0%B8%A3%E0%B8%B5%E0%B8%A2%E0%B8%B2-%E0%B8%9E%E0%B8%A3%E0%B8%AD%E0%B8%9E%E0%B9%80%E0%B8%9E%E0%B8%AD%E0%B8%A3%E0%B9%8C%E0%B8%95%E0%B8%B5%E0%B9%89-x-%E0%B8%9B%E0%B9%8A%E0%B8%AD\\\/#primaryimage\",\"url\":\"https:\\\/\\\/areeya.co.th\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/cover-d-81.jpg\",\"contentUrl\":\"https:\\\/\\\/areeya.co.th\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/cover-d-81.jpg\",\"width\":1200,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/areeya.co.th\\\/en\\\/news-events\\\/%E0%B8%AD%E0%B8%B2%E0%B8%A3%E0%B8%B5%E0%B8%A2%E0%B8%B2-%E0%B8%9E%E0%B8%A3%E0%B8%AD%E0%B8%9E%E0%B9%80%E0%B8%9E%E0%B8%AD%E0%B8%A3%E0%B9%8C%E0%B8%95%E0%B8%B5%E0%B9%89-x-%E0%B8%9B%E0%B9%8A%E0%B8%AD\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/areeya.co.th\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e2d\u0e32\u0e23\u0e35\u0e22\u0e32 \u0e1e\u0e23\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 x \u0e1b\u0e4a\u0e2d\u0e04\u0e42\u0e04 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e2d\u0e31\u0e14\u0e42\u0e1b\u0e23\u0e2f \u0e41\u0e23\u0e07 \u201cCOLORS FREEVERRR\u201d \u0e0b\u0e37\u0e49\u0e2d\u0e1a\u0e49\u0e32\u0e19\u0e41\u0e16\u0e21\u0e23\u0e16\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/areeya.co.th\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/areeya.co.th\\\/en\\\/\",\"name\":\"\u0e2d\u0e32\u0e23\u0e35\u0e22\u0e32 \u0e1e\u0e23\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/areeya.co.th\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/areeya.co.th\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/areeya.co.th\\\/en\\\/#organization\",\"name\":\"\u0e2d\u0e32\u0e23\u0e35\u0e22\u0e32 \u0e1e\u0e23\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49\",\"url\":\"https:\\\/\\\/areeya.co.th\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/areeya.co.th\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/areeya.co.th\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/areeya.svg\",\"contentUrl\":\"https:\\\/\\\/areeya.co.th\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/areeya.svg\",\"width\":100,\"height\":40,\"caption\":\"\u0e2d\u0e32\u0e23\u0e35\u0e22\u0e32 \u0e1e\u0e23\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49\"},\"image\":{\"@id\":\"https:\\\/\\\/areeya.co.th\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Areeya joins hands with Pocco to launches \u201cCOLORS FREEVERRR\" | \u0e2d\u0e32\u0e23\u0e35\u0e22\u0e32 \u0e1e\u0e23\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/areeya.co.th\/en\/news-events\/\u0e2d\u0e32\u0e23\u0e35\u0e22\u0e32-\u0e1e\u0e23\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49-x-\u0e1b\u0e4a\u0e2d\/","og_locale":"en_US","og_type":"article","og_title":"Areeya joins hands with Pocco to launches \u201cCOLORS FREEVERRR\" | \u0e2d\u0e32\u0e23\u0e35\u0e22\u0e32 \u0e1e\u0e23\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49","og_description":"\u0e2d\u0e32\u0e23\u0e35\u0e22\u0e32 \u0e1e\u0e23\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 x \u0e1b\u0e4a\u0e2d\u0e04\u0e42\u0e04 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e2d\u0e31\u0e14\u0e42\u0e1b\u0e23\u0e2f \u0e41\u0e23\u0e07 \u201cCOLORS FREEVERRR\u201d \u0e0b\u0e37\u0e49\u0e2d\u0e1a\u0e49\u0e32\u0e19\u0e41\u0e16\u0e21\u0e23\u0e16 \u0e2d\u0e32\u0e23\u0e35\u0e22\u0e32\u00a0\u0e1e\u0e23\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e1c\u0e39\u0e49\u0e19\u0e33\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e17\u0e35\u0e48\u0e15\u0e2d\u0e1a\u0e42\u0e08\u0e17\u0e22\u0e4c\u0e44\u0e25\u0e1f\u0e4c\u0e2a\u0e44\u0e15\u0e25\u0e4c\u0e17\u0e35\u0e48\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e04\u0e19 (Lifestyle Property Developer) \u0e42\u0e14\u0e22 \u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e1e\u0e31\u0e17\u0e18\u0e21\u0e25 \u0e40\u0e25\u0e32\u0e2b\u0e1e\u0e39\u0e19\u0e23\u0e31\u0e07\u0e29\u0e35\u00a0\u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e2d\u0e32\u0e27\u0e38\u0e42\u0e2a \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u00a0\u0e2d\u0e32\u0e23\u0e35\u0e22\u0e32\u00a0\u0e1e\u0e23\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\u00a0(\u0e21\u0e2b\u0e32\u0e0a\u0e19)\u00a0\u0e08\u0e31\u0e1a\u0e21\u0e37\u0e2d \u0e1b\u0e4a\u0e2d\u0e04\u0e42\u0e04 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e42\u0e14\u0e22 BRG Group \u0e1c\u0e39\u0e49\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e02\u0e19\u0e32\u0e14\u0e40\u0e25\u0e47\u0e01 \u0e2a\u0e38\u0e14\u0e19\u0e48\u0e32\u0e23\u0e31\u0e01 \u0e40\u0e2b\u0e21\u0e32\u0e30\u0e01\u0e31\u0e1a\u0e44\u0e25\u0e1f\u0e4c\u0e2a\u0e44\u0e15\u0e25\u0e4c\u0e43\u0e19\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e42\u0e14\u0e22 \u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e2d\u0e31\u0e08\u0e08\u0e34\u0e21\u0e32 \u0e28\u0e23\u0e35\u0e23\u0e31\u0e15\u0e19\u0e1b\u0e23\u0e30\u0e20\u0e32\u0e2a \u0e41\u0e25\u0e30 \u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e0a\u0e25\u0e25\u0e18\u0e23 \u0e28\u0e23\u0e35\u0e23\u0e31\u0e15\u0e19\u0e1b\u0e23\u0e30\u0e20\u0e32\u0e2a \u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e1b\u0e4a\u0e2d\u0e04\u0e42\u0e04 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14 \u0e21\u0e2d\u0e1a\u0e42\u0e1b\u0e23\u0e42\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e38\u0e14\u0e1e\u0e34\u0e40\u0e28\u0e29 \u0e17\u0e35\u0e48\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e40\u0e15\u0e34\u0e21\u0e40\u0e15\u0e47\u0e21\u0e2a\u0e35\u0e2a\u0e31\u0e19\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e04\u0e19\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e43\u0e19\u0e41\u0e04\u0e21\u0e40\u0e1b\u0e0d \u201cCOLORS FREEVERRR\u201d \u0e0b\u0e37\u0e49\u0e2d\u0e1a\u0e49\u0e32\u0e19\u0e41\u0e16\u0e21\u0e23\u0e16* \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e08\u0e2d\u0e07 \u0e41\u0e25\u0e30\u0e42\u0e2d\u0e19\u0e2f \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e40\u0e14\u0e2d\u0e30 \u0e04\u0e31\u0e25\u0e40\u0e25\u0e2d\u0e23\u0e4c\u0e2a \u0e17\u0e32\u0e27\u0e19\u0e4c\u0e42\u0e2e\u0e21\u0e43\u0e2b\u0e0d\u0e48 \u0e43\u0e2b\u0e49\u0e04\u0e38\u0e13\u0e43\u0e0a\u0e49\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e44\u0e14\u0e49\u0e40\u0e15\u0e47\u0e21\u0e17\u0e35\u0e48 \u0e1a\u0e19 4 \u0e17\u0e33\u0e40\u0e25\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e \u0e1a\u0e32\u0e07\u0e19\u0e32,...","og_url":"https:\/\/areeya.co.th\/en\/news-events\/\u0e2d\u0e32\u0e23\u0e35\u0e22\u0e32-\u0e1e\u0e23\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49-x-\u0e1b\u0e4a\u0e2d\/","og_site_name":"\u0e2d\u0e32\u0e23\u0e35\u0e22\u0e32 \u0e1e\u0e23\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49","article_modified_time":"2023-05-29T06:05:03+00:00","og_image":[{"width":1200,"height":700,"url":"https:\/\/areeya.co.th\/wp-content\/uploads\/2023\/05\/cover-d-81.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/areeya.co.th\/en\/news-events\/%E0%B8%AD%E0%B8%B2%E0%B8%A3%E0%B8%B5%E0%B8%A2%E0%B8%B2-%E0%B8%9E%E0%B8%A3%E0%B8%AD%E0%B8%9E%E0%B9%80%E0%B8%9E%E0%B8%AD%E0%B8%A3%E0%B9%8C%E0%B8%95%E0%B8%B5%E0%B9%89-x-%E0%B8%9B%E0%B9%8A%E0%B8%AD\/","url":"https:\/\/areeya.co.th\/en\/news-events\/%E0%B8%AD%E0%B8%B2%E0%B8%A3%E0%B8%B5%E0%B8%A2%E0%B8%B2-%E0%B8%9E%E0%B8%A3%E0%B8%AD%E0%B8%9E%E0%B9%80%E0%B8%9E%E0%B8%AD%E0%B8%A3%E0%B9%8C%E0%B8%95%E0%B8%B5%E0%B9%89-x-%E0%B8%9B%E0%B9%8A%E0%B8%AD\/","name":"Areeya joins hands with Pocco to launches \u201cCOLORS FREEVERRR\" | \u0e2d\u0e32\u0e23\u0e35\u0e22\u0e32 \u0e1e\u0e23\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49","isPartOf":{"@id":"https:\/\/areeya.co.th\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/areeya.co.th\/en\/news-events\/%E0%B8%AD%E0%B8%B2%E0%B8%A3%E0%B8%B5%E0%B8%A2%E0%B8%B2-%E0%B8%9E%E0%B8%A3%E0%B8%AD%E0%B8%9E%E0%B9%80%E0%B8%9E%E0%B8%AD%E0%B8%A3%E0%B9%8C%E0%B8%95%E0%B8%B5%E0%B9%89-x-%E0%B8%9B%E0%B9%8A%E0%B8%AD\/#primaryimage"},"image":{"@id":"https:\/\/areeya.co.th\/en\/news-events\/%E0%B8%AD%E0%B8%B2%E0%B8%A3%E0%B8%B5%E0%B8%A2%E0%B8%B2-%E0%B8%9E%E0%B8%A3%E0%B8%AD%E0%B8%9E%E0%B9%80%E0%B8%9E%E0%B8%AD%E0%B8%A3%E0%B9%8C%E0%B8%95%E0%B8%B5%E0%B9%89-x-%E0%B8%9B%E0%B9%8A%E0%B8%AD\/#primaryimage"},"thumbnailUrl":"https:\/\/areeya.co.th\/wp-content\/uploads\/2023\/05\/cover-d-81.jpg","datePublished":"2023-05-29T06:04:00+00:00","dateModified":"2023-05-29T06:05:03+00:00","breadcrumb":{"@id":"https:\/\/areeya.co.th\/en\/news-events\/%E0%B8%AD%E0%B8%B2%E0%B8%A3%E0%B8%B5%E0%B8%A2%E0%B8%B2-%E0%B8%9E%E0%B8%A3%E0%B8%AD%E0%B8%9E%E0%B9%80%E0%B8%9E%E0%B8%AD%E0%B8%A3%E0%B9%8C%E0%B8%95%E0%B8%B5%E0%B9%89-x-%E0%B8%9B%E0%B9%8A%E0%B8%AD\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/areeya.co.th\/en\/news-events\/%E0%B8%AD%E0%B8%B2%E0%B8%A3%E0%B8%B5%E0%B8%A2%E0%B8%B2-%E0%B8%9E%E0%B8%A3%E0%B8%AD%E0%B8%9E%E0%B9%80%E0%B8%9E%E0%B8%AD%E0%B8%A3%E0%B9%8C%E0%B8%95%E0%B8%B5%E0%B9%89-x-%E0%B8%9B%E0%B9%8A%E0%B8%AD\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/areeya.co.th\/en\/news-events\/%E0%B8%AD%E0%B8%B2%E0%B8%A3%E0%B8%B5%E0%B8%A2%E0%B8%B2-%E0%B8%9E%E0%B8%A3%E0%B8%AD%E0%B8%9E%E0%B9%80%E0%B8%9E%E0%B8%AD%E0%B8%A3%E0%B9%8C%E0%B8%95%E0%B8%B5%E0%B9%89-x-%E0%B8%9B%E0%B9%8A%E0%B8%AD\/#primaryimage","url":"https:\/\/areeya.co.th\/wp-content\/uploads\/2023\/05\/cover-d-81.jpg","contentUrl":"https:\/\/areeya.co.th\/wp-content\/uploads\/2023\/05\/cover-d-81.jpg","width":1200,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/areeya.co.th\/en\/news-events\/%E0%B8%AD%E0%B8%B2%E0%B8%A3%E0%B8%B5%E0%B8%A2%E0%B8%B2-%E0%B8%9E%E0%B8%A3%E0%B8%AD%E0%B8%9E%E0%B9%80%E0%B8%9E%E0%B8%AD%E0%B8%A3%E0%B9%8C%E0%B8%95%E0%B8%B5%E0%B9%89-x-%E0%B8%9B%E0%B9%8A%E0%B8%AD\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/areeya.co.th\/en\/"},{"@type":"ListItem","position":2,"name":"\u0e2d\u0e32\u0e23\u0e35\u0e22\u0e32 \u0e1e\u0e23\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 x \u0e1b\u0e4a\u0e2d\u0e04\u0e42\u0e04 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e2d\u0e31\u0e14\u0e42\u0e1b\u0e23\u0e2f \u0e41\u0e23\u0e07 \u201cCOLORS FREEVERRR\u201d \u0e0b\u0e37\u0e49\u0e2d\u0e1a\u0e49\u0e32\u0e19\u0e41\u0e16\u0e21\u0e23\u0e16"}]},{"@type":"WebSite","@id":"https:\/\/areeya.co.th\/en\/#website","url":"https:\/\/areeya.co.th\/en\/","name":"\u0e2d\u0e32\u0e23\u0e35\u0e22\u0e32 \u0e1e\u0e23\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49","description":"","publisher":{"@id":"https:\/\/areeya.co.th\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/areeya.co.th\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/areeya.co.th\/en\/#organization","name":"\u0e2d\u0e32\u0e23\u0e35\u0e22\u0e32 \u0e1e\u0e23\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49","url":"https:\/\/areeya.co.th\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/areeya.co.th\/en\/#\/schema\/logo\/image\/","url":"https:\/\/areeya.co.th\/wp-content\/uploads\/2023\/03\/areeya.svg","contentUrl":"https:\/\/areeya.co.th\/wp-content\/uploads\/2023\/03\/areeya.svg","width":100,"height":40,"caption":"\u0e2d\u0e32\u0e23\u0e35\u0e22\u0e32 \u0e1e\u0e23\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49"},"image":{"@id":"https:\/\/areeya.co.th\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/areeya.co.th\/en\/wp-json\/wp\/v2\/news-events\/12384","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/areeya.co.th\/en\/wp-json\/wp\/v2\/news-events"}],"about":[{"href":"https:\/\/areeya.co.th\/en\/wp-json\/wp\/v2\/types\/news-events"}],"author":[{"embeddable":true,"href":"https:\/\/areeya.co.th\/en\/wp-json\/wp\/v2\/users\/6"}],"version-history":[{"count":1,"href":"https:\/\/areeya.co.th\/en\/wp-json\/wp\/v2\/news-events\/12384\/revisions"}],"predecessor-version":[{"id":12385,"href":"https:\/\/areeya.co.th\/en\/wp-json\/wp\/v2\/news-events\/12384\/revisions\/12385"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/areeya.co.th\/en\/wp-json\/wp\/v2\/media\/12373"}],"wp:attachment":[{"href":"https:\/\/areeya.co.th\/en\/wp-json\/wp\/v2\/media?parent=12384"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}