{"id":11979,"date":"2023-05-29T10:18:45","date_gmt":"2023-05-29T03:18:45","guid":{"rendered":"https:\/\/areeya.co.th\/news-events\/%e0%b8%97%e0%b8%b1%e0%b8%99%e0%b8%ab%e0%b8%b8%e0%b9%89%e0%b8%99-a%e0%b8%88%e0%b9%88%e0%b8%ad%e0%b8%ad%e0%b8%ad%e0%b8%81%e0%b8%ab%e0%b8%b8%e0%b9%89%e0%b8%99%e0%b8%81%e0%b8%b9%e0%b9%891%e0%b8%9e\/"},"modified":"2023-05-29T10:18:45","modified_gmt":"2023-05-29T03:18:45","slug":"%e0%b8%97%e0%b8%b1%e0%b8%99%e0%b8%ab%e0%b8%b8%e0%b9%89%e0%b8%99-a%e0%b8%88%e0%b9%88%e0%b8%ad%e0%b8%ad%e0%b8%ad%e0%b8%81%e0%b8%ab%e0%b8%b8%e0%b9%89%e0%b8%99%e0%b8%81%e0%b8%b9%e0%b9%891%e0%b8%9e","status":"publish","type":"news-events","link":"https:\/\/areeya.co.th\/en\/news-events\/%E0%B8%97%E0%B8%B1%E0%B8%99%E0%B8%AB%E0%B8%B8%E0%B9%89%E0%B8%99-a%E0%B8%88%E0%B9%88%E0%B8%AD%E0%B8%AD%E0%B8%AD%E0%B8%81%E0%B8%AB%E0%B8%B8%E0%B9%89%E0%B8%99%E0%B8%81%E0%B8%B9%E0%B9%891%E0%B8%9E\/","title":{"rendered":"\u0e17\u0e31\u0e19\u0e2b\u0e38\u0e49\u0e19 : A\u0e08\u0e48\u0e2d\u0e2d\u0e2d\u0e01\u0e2b\u0e38\u0e49\u0e19\u0e01\u0e39\u0e491\u0e1e\u0e31\u0e19\u0e25.\u0e02\u0e32\u0e22\u0e19\u0e25\u0e17.\u0e23\u0e32\u0e22\u0e43\u0e2b\u0e0d\u0e48\u0e0a\u0e39\u0e2d\u0e31\u0e15\u0e23\u0e32\u0e14\u0e2d\u0e01\u0e40\u0e1a\u0e35\u0e49\u0e227%"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-11969\" src=\"https:\/\/areeya.co.th\/wp-content\/uploads\/2023\/05\/c1-101.jpg\" alt=\"\" width=\"425\" height=\"871\" srcset=\"https:\/\/areeya.co.th\/wp-content\/uploads\/2023\/05\/c1-101.jpg 425w, https:\/\/areeya.co.th\/wp-content\/uploads\/2023\/05\/c1-101-146x300.jpg 146w\" sizes=\"auto, (max-width: 425px) 100vw, 425px\" \/><\/p>\n<p><strong>\u0e2d\u0e32\u0e23\u0e35\u0e22\u0e32 \u0e1e\u0e23\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e02\u0e2d\u0e02\u0e2d\u0e1a\u0e04\u0e38\u0e13\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e08\u0e32\u0e01<\/strong><br \/>\n\u0e17\u0e31\u0e19\u0e2b\u0e38\u0e49\u0e19 : \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 1 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 2563<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e2d\u0e32\u0e23\u0e35\u0e22\u0e32 \u0e1e\u0e23\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e02\u0e2d\u0e02\u0e2d\u0e1a\u0e04\u0e38\u0e13\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e08\u0e32\u0e01 \u0e17\u0e31\u0e19\u0e2b\u0e38\u0e49\u0e19 : \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 1 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 2563<\/p>\n","protected":false},"author":6,"featured_media":11974,"template":"","class_list":["post-11979","news-events","type-news-events","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0e17\u0e31\u0e19\u0e2b\u0e38\u0e49\u0e19 : A\u0e08\u0e48\u0e2d\u0e2d\u0e2d\u0e01\u0e2b\u0e38\u0e49\u0e19\u0e01\u0e39\u0e491\u0e1e\u0e31\u0e19\u0e25.\u0e02\u0e32\u0e22\u0e19\u0e25\u0e17.\u0e23\u0e32\u0e22\u0e43\u0e2b\u0e0d\u0e48\u0e0a\u0e39\u0e2d\u0e31\u0e15\u0e23\u0e32\u0e14\u0e2d\u0e01\u0e40\u0e1a\u0e35\u0e49\u0e227% | \u0e2d\u0e32\u0e23\u0e35\u0e22\u0e32 \u0e1e\u0e23\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/areeya.co.th\/en\/news-events\/\u0e17\u0e31\u0e19\u0e2b\u0e38\u0e49\u0e19-a\u0e08\u0e48\u0e2d\u0e2d\u0e2d\u0e01\u0e2b\u0e38\u0e49\u0e19\u0e01\u0e39\u0e491\u0e1e\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e17\u0e31\u0e19\u0e2b\u0e38\u0e49\u0e19 : A\u0e08\u0e48\u0e2d\u0e2d\u0e2d\u0e01\u0e2b\u0e38\u0e49\u0e19\u0e01\u0e39\u0e491\u0e1e\u0e31\u0e19\u0e25.\u0e02\u0e32\u0e22\u0e19\u0e25\u0e17.\u0e23\u0e32\u0e22\u0e43\u0e2b\u0e0d\u0e48\u0e0a\u0e39\u0e2d\u0e31\u0e15\u0e23\u0e32\u0e14\u0e2d\u0e01\u0e40\u0e1a\u0e35\u0e49\u0e227% | \u0e2d\u0e32\u0e23\u0e35\u0e22\u0e32 \u0e1e\u0e23\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49\" \/>\n<meta property=\"og:description\" content=\"\u0e2d\u0e32\u0e23\u0e35\u0e22\u0e32 \u0e1e\u0e23\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e02\u0e2d\u0e02\u0e2d\u0e1a\u0e04\u0e38\u0e13\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e08\u0e32\u0e01 \u0e17\u0e31\u0e19\u0e2b\u0e38\u0e49\u0e19 : \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 1 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 2563\" \/>\n<meta property=\"og:url\" content=\"https:\/\/areeya.co.th\/en\/news-events\/\u0e17\u0e31\u0e19\u0e2b\u0e38\u0e49\u0e19-a\u0e08\u0e48\u0e2d\u0e2d\u0e2d\u0e01\u0e2b\u0e38\u0e49\u0e19\u0e01\u0e39\u0e491\u0e1e\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0e2d\u0e32\u0e23\u0e35\u0e22\u0e32 \u0e1e\u0e23\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49\" \/>\n<meta property=\"og:image\" content=\"https:\/\/areeya.co.th\/wp-content\/uploads\/2023\/05\/c1-101.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/areeya.co.th\\\/en\\\/news-events\\\/%E0%B8%97%E0%B8%B1%E0%B8%99%E0%B8%AB%E0%B8%B8%E0%B9%89%E0%B8%99-a%E0%B8%88%E0%B9%88%E0%B8%AD%E0%B8%AD%E0%B8%AD%E0%B8%81%E0%B8%AB%E0%B8%B8%E0%B9%89%E0%B8%99%E0%B8%81%E0%B8%B9%E0%B9%891%E0%B8%9E\\\/\",\"url\":\"https:\\\/\\\/areeya.co.th\\\/en\\\/news-events\\\/%E0%B8%97%E0%B8%B1%E0%B8%99%E0%B8%AB%E0%B8%B8%E0%B9%89%E0%B8%99-a%E0%B8%88%E0%B9%88%E0%B8%AD%E0%B8%AD%E0%B8%AD%E0%B8%81%E0%B8%AB%E0%B8%B8%E0%B9%89%E0%B8%99%E0%B8%81%E0%B8%B9%E0%B9%891%E0%B8%9E\\\/\",\"name\":\"\u0e17\u0e31\u0e19\u0e2b\u0e38\u0e49\u0e19 : A\u0e08\u0e48\u0e2d\u0e2d\u0e2d\u0e01\u0e2b\u0e38\u0e49\u0e19\u0e01\u0e39\u0e491\u0e1e\u0e31\u0e19\u0e25.\u0e02\u0e32\u0e22\u0e19\u0e25\u0e17.\u0e23\u0e32\u0e22\u0e43\u0e2b\u0e0d\u0e48\u0e0a\u0e39\u0e2d\u0e31\u0e15\u0e23\u0e32\u0e14\u0e2d\u0e01\u0e40\u0e1a\u0e35\u0e49\u0e227% | \u0e2d\u0e32\u0e23\u0e35\u0e22\u0e32 \u0e1e\u0e23\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/areeya.co.th\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/areeya.co.th\\\/en\\\/news-events\\\/%E0%B8%97%E0%B8%B1%E0%B8%99%E0%B8%AB%E0%B8%B8%E0%B9%89%E0%B8%99-a%E0%B8%88%E0%B9%88%E0%B8%AD%E0%B8%AD%E0%B8%AD%E0%B8%81%E0%B8%AB%E0%B8%B8%E0%B9%89%E0%B8%99%E0%B8%81%E0%B8%B9%E0%B9%891%E0%B8%9E\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/areeya.co.th\\\/en\\\/news-events\\\/%E0%B8%97%E0%B8%B1%E0%B8%99%E0%B8%AB%E0%B8%B8%E0%B9%89%E0%B8%99-a%E0%B8%88%E0%B9%88%E0%B8%AD%E0%B8%AD%E0%B8%AD%E0%B8%81%E0%B8%AB%E0%B8%B8%E0%B9%89%E0%B8%99%E0%B8%81%E0%B8%B9%E0%B9%891%E0%B8%9E\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/areeya.co.th\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/cover-d-62.jpg\",\"datePublished\":\"2023-05-29T03:18:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/areeya.co.th\\\/en\\\/news-events\\\/%E0%B8%97%E0%B8%B1%E0%B8%99%E0%B8%AB%E0%B8%B8%E0%B9%89%E0%B8%99-a%E0%B8%88%E0%B9%88%E0%B8%AD%E0%B8%AD%E0%B8%AD%E0%B8%81%E0%B8%AB%E0%B8%B8%E0%B9%89%E0%B8%99%E0%B8%81%E0%B8%B9%E0%B9%891%E0%B8%9E\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/areeya.co.th\\\/en\\\/news-events\\\/%E0%B8%97%E0%B8%B1%E0%B8%99%E0%B8%AB%E0%B8%B8%E0%B9%89%E0%B8%99-a%E0%B8%88%E0%B9%88%E0%B8%AD%E0%B8%AD%E0%B8%AD%E0%B8%81%E0%B8%AB%E0%B8%B8%E0%B9%89%E0%B8%99%E0%B8%81%E0%B8%B9%E0%B9%891%E0%B8%9E\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/areeya.co.th\\\/en\\\/news-events\\\/%E0%B8%97%E0%B8%B1%E0%B8%99%E0%B8%AB%E0%B8%B8%E0%B9%89%E0%B8%99-a%E0%B8%88%E0%B9%88%E0%B8%AD%E0%B8%AD%E0%B8%AD%E0%B8%81%E0%B8%AB%E0%B8%B8%E0%B9%89%E0%B8%99%E0%B8%81%E0%B8%B9%E0%B9%891%E0%B8%9E\\\/#primaryimage\",\"url\":\"https:\\\/\\\/areeya.co.th\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/cover-d-62.jpg\",\"contentUrl\":\"https:\\\/\\\/areeya.co.th\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/cover-d-62.jpg\",\"width\":1200,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/areeya.co.th\\\/en\\\/news-events\\\/%E0%B8%97%E0%B8%B1%E0%B8%99%E0%B8%AB%E0%B8%B8%E0%B9%89%E0%B8%99-a%E0%B8%88%E0%B9%88%E0%B8%AD%E0%B8%AD%E0%B8%AD%E0%B8%81%E0%B8%AB%E0%B8%B8%E0%B9%89%E0%B8%99%E0%B8%81%E0%B8%B9%E0%B9%891%E0%B8%9E\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/areeya.co.th\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e17\u0e31\u0e19\u0e2b\u0e38\u0e49\u0e19 : A\u0e08\u0e48\u0e2d\u0e2d\u0e2d\u0e01\u0e2b\u0e38\u0e49\u0e19\u0e01\u0e39\u0e491\u0e1e\u0e31\u0e19\u0e25.\u0e02\u0e32\u0e22\u0e19\u0e25\u0e17.\u0e23\u0e32\u0e22\u0e43\u0e2b\u0e0d\u0e48\u0e0a\u0e39\u0e2d\u0e31\u0e15\u0e23\u0e32\u0e14\u0e2d\u0e01\u0e40\u0e1a\u0e35\u0e49\u0e227%\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/areeya.co.th\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/areeya.co.th\\\/en\\\/\",\"name\":\"\u0e2d\u0e32\u0e23\u0e35\u0e22\u0e32 \u0e1e\u0e23\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/areeya.co.th\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/areeya.co.th\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/areeya.co.th\\\/en\\\/#organization\",\"name\":\"\u0e2d\u0e32\u0e23\u0e35\u0e22\u0e32 \u0e1e\u0e23\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49\",\"url\":\"https:\\\/\\\/areeya.co.th\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/areeya.co.th\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/areeya.co.th\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/areeya.svg\",\"contentUrl\":\"https:\\\/\\\/areeya.co.th\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/areeya.svg\",\"width\":100,\"height\":40,\"caption\":\"\u0e2d\u0e32\u0e23\u0e35\u0e22\u0e32 \u0e1e\u0e23\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49\"},\"image\":{\"@id\":\"https:\\\/\\\/areeya.co.th\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e17\u0e31\u0e19\u0e2b\u0e38\u0e49\u0e19 : A\u0e08\u0e48\u0e2d\u0e2d\u0e2d\u0e01\u0e2b\u0e38\u0e49\u0e19\u0e01\u0e39\u0e491\u0e1e\u0e31\u0e19\u0e25.\u0e02\u0e32\u0e22\u0e19\u0e25\u0e17.\u0e23\u0e32\u0e22\u0e43\u0e2b\u0e0d\u0e48\u0e0a\u0e39\u0e2d\u0e31\u0e15\u0e23\u0e32\u0e14\u0e2d\u0e01\u0e40\u0e1a\u0e35\u0e49\u0e227% | \u0e2d\u0e32\u0e23\u0e35\u0e22\u0e32 \u0e1e\u0e23\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/areeya.co.th\/en\/news-events\/\u0e17\u0e31\u0e19\u0e2b\u0e38\u0e49\u0e19-a\u0e08\u0e48\u0e2d\u0e2d\u0e2d\u0e01\u0e2b\u0e38\u0e49\u0e19\u0e01\u0e39\u0e491\u0e1e\/","og_locale":"en_US","og_type":"article","og_title":"\u0e17\u0e31\u0e19\u0e2b\u0e38\u0e49\u0e19 : A\u0e08\u0e48\u0e2d\u0e2d\u0e2d\u0e01\u0e2b\u0e38\u0e49\u0e19\u0e01\u0e39\u0e491\u0e1e\u0e31\u0e19\u0e25.\u0e02\u0e32\u0e22\u0e19\u0e25\u0e17.\u0e23\u0e32\u0e22\u0e43\u0e2b\u0e0d\u0e48\u0e0a\u0e39\u0e2d\u0e31\u0e15\u0e23\u0e32\u0e14\u0e2d\u0e01\u0e40\u0e1a\u0e35\u0e49\u0e227% | \u0e2d\u0e32\u0e23\u0e35\u0e22\u0e32 \u0e1e\u0e23\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49","og_description":"\u0e2d\u0e32\u0e23\u0e35\u0e22\u0e32 \u0e1e\u0e23\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e02\u0e2d\u0e02\u0e2d\u0e1a\u0e04\u0e38\u0e13\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e08\u0e32\u0e01 \u0e17\u0e31\u0e19\u0e2b\u0e38\u0e49\u0e19 : \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 1 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 2563","og_url":"https:\/\/areeya.co.th\/en\/news-events\/\u0e17\u0e31\u0e19\u0e2b\u0e38\u0e49\u0e19-a\u0e08\u0e48\u0e2d\u0e2d\u0e2d\u0e01\u0e2b\u0e38\u0e49\u0e19\u0e01\u0e39\u0e491\u0e1e\/","og_site_name":"\u0e2d\u0e32\u0e23\u0e35\u0e22\u0e32 \u0e1e\u0e23\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49","og_image":[{"url":"https:\/\/areeya.co.th\/wp-content\/uploads\/2023\/05\/c1-101.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/areeya.co.th\/en\/news-events\/%E0%B8%97%E0%B8%B1%E0%B8%99%E0%B8%AB%E0%B8%B8%E0%B9%89%E0%B8%99-a%E0%B8%88%E0%B9%88%E0%B8%AD%E0%B8%AD%E0%B8%AD%E0%B8%81%E0%B8%AB%E0%B8%B8%E0%B9%89%E0%B8%99%E0%B8%81%E0%B8%B9%E0%B9%891%E0%B8%9E\/","url":"https:\/\/areeya.co.th\/en\/news-events\/%E0%B8%97%E0%B8%B1%E0%B8%99%E0%B8%AB%E0%B8%B8%E0%B9%89%E0%B8%99-a%E0%B8%88%E0%B9%88%E0%B8%AD%E0%B8%AD%E0%B8%AD%E0%B8%81%E0%B8%AB%E0%B8%B8%E0%B9%89%E0%B8%99%E0%B8%81%E0%B8%B9%E0%B9%891%E0%B8%9E\/","name":"\u0e17\u0e31\u0e19\u0e2b\u0e38\u0e49\u0e19 : A\u0e08\u0e48\u0e2d\u0e2d\u0e2d\u0e01\u0e2b\u0e38\u0e49\u0e19\u0e01\u0e39\u0e491\u0e1e\u0e31\u0e19\u0e25.\u0e02\u0e32\u0e22\u0e19\u0e25\u0e17.\u0e23\u0e32\u0e22\u0e43\u0e2b\u0e0d\u0e48\u0e0a\u0e39\u0e2d\u0e31\u0e15\u0e23\u0e32\u0e14\u0e2d\u0e01\u0e40\u0e1a\u0e35\u0e49\u0e227% | \u0e2d\u0e32\u0e23\u0e35\u0e22\u0e32 \u0e1e\u0e23\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49","isPartOf":{"@id":"https:\/\/areeya.co.th\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/areeya.co.th\/en\/news-events\/%E0%B8%97%E0%B8%B1%E0%B8%99%E0%B8%AB%E0%B8%B8%E0%B9%89%E0%B8%99-a%E0%B8%88%E0%B9%88%E0%B8%AD%E0%B8%AD%E0%B8%AD%E0%B8%81%E0%B8%AB%E0%B8%B8%E0%B9%89%E0%B8%99%E0%B8%81%E0%B8%B9%E0%B9%891%E0%B8%9E\/#primaryimage"},"image":{"@id":"https:\/\/areeya.co.th\/en\/news-events\/%E0%B8%97%E0%B8%B1%E0%B8%99%E0%B8%AB%E0%B8%B8%E0%B9%89%E0%B8%99-a%E0%B8%88%E0%B9%88%E0%B8%AD%E0%B8%AD%E0%B8%AD%E0%B8%81%E0%B8%AB%E0%B8%B8%E0%B9%89%E0%B8%99%E0%B8%81%E0%B8%B9%E0%B9%891%E0%B8%9E\/#primaryimage"},"thumbnailUrl":"https:\/\/areeya.co.th\/wp-content\/uploads\/2023\/05\/cover-d-62.jpg","datePublished":"2023-05-29T03:18:45+00:00","breadcrumb":{"@id":"https:\/\/areeya.co.th\/en\/news-events\/%E0%B8%97%E0%B8%B1%E0%B8%99%E0%B8%AB%E0%B8%B8%E0%B9%89%E0%B8%99-a%E0%B8%88%E0%B9%88%E0%B8%AD%E0%B8%AD%E0%B8%AD%E0%B8%81%E0%B8%AB%E0%B8%B8%E0%B9%89%E0%B8%99%E0%B8%81%E0%B8%B9%E0%B9%891%E0%B8%9E\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/areeya.co.th\/en\/news-events\/%E0%B8%97%E0%B8%B1%E0%B8%99%E0%B8%AB%E0%B8%B8%E0%B9%89%E0%B8%99-a%E0%B8%88%E0%B9%88%E0%B8%AD%E0%B8%AD%E0%B8%AD%E0%B8%81%E0%B8%AB%E0%B8%B8%E0%B9%89%E0%B8%99%E0%B8%81%E0%B8%B9%E0%B9%891%E0%B8%9E\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/areeya.co.th\/en\/news-events\/%E0%B8%97%E0%B8%B1%E0%B8%99%E0%B8%AB%E0%B8%B8%E0%B9%89%E0%B8%99-a%E0%B8%88%E0%B9%88%E0%B8%AD%E0%B8%AD%E0%B8%AD%E0%B8%81%E0%B8%AB%E0%B8%B8%E0%B9%89%E0%B8%99%E0%B8%81%E0%B8%B9%E0%B9%891%E0%B8%9E\/#primaryimage","url":"https:\/\/areeya.co.th\/wp-content\/uploads\/2023\/05\/cover-d-62.jpg","contentUrl":"https:\/\/areeya.co.th\/wp-content\/uploads\/2023\/05\/cover-d-62.jpg","width":1200,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/areeya.co.th\/en\/news-events\/%E0%B8%97%E0%B8%B1%E0%B8%99%E0%B8%AB%E0%B8%B8%E0%B9%89%E0%B8%99-a%E0%B8%88%E0%B9%88%E0%B8%AD%E0%B8%AD%E0%B8%AD%E0%B8%81%E0%B8%AB%E0%B8%B8%E0%B9%89%E0%B8%99%E0%B8%81%E0%B8%B9%E0%B9%891%E0%B8%9E\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/areeya.co.th\/en\/"},{"@type":"ListItem","position":2,"name":"\u0e17\u0e31\u0e19\u0e2b\u0e38\u0e49\u0e19 : A\u0e08\u0e48\u0e2d\u0e2d\u0e2d\u0e01\u0e2b\u0e38\u0e49\u0e19\u0e01\u0e39\u0e491\u0e1e\u0e31\u0e19\u0e25.\u0e02\u0e32\u0e22\u0e19\u0e25\u0e17.\u0e23\u0e32\u0e22\u0e43\u0e2b\u0e0d\u0e48\u0e0a\u0e39\u0e2d\u0e31\u0e15\u0e23\u0e32\u0e14\u0e2d\u0e01\u0e40\u0e1a\u0e35\u0e49\u0e227%"}]},{"@type":"WebSite","@id":"https:\/\/areeya.co.th\/en\/#website","url":"https:\/\/areeya.co.th\/en\/","name":"\u0e2d\u0e32\u0e23\u0e35\u0e22\u0e32 \u0e1e\u0e23\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49","description":"","publisher":{"@id":"https:\/\/areeya.co.th\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/areeya.co.th\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/areeya.co.th\/en\/#organization","name":"\u0e2d\u0e32\u0e23\u0e35\u0e22\u0e32 \u0e1e\u0e23\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49","url":"https:\/\/areeya.co.th\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/areeya.co.th\/en\/#\/schema\/logo\/image\/","url":"https:\/\/areeya.co.th\/wp-content\/uploads\/2023\/03\/areeya.svg","contentUrl":"https:\/\/areeya.co.th\/wp-content\/uploads\/2023\/03\/areeya.svg","width":100,"height":40,"caption":"\u0e2d\u0e32\u0e23\u0e35\u0e22\u0e32 \u0e1e\u0e23\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49"},"image":{"@id":"https:\/\/areeya.co.th\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/areeya.co.th\/en\/wp-json\/wp\/v2\/news-events\/11979","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/areeya.co.th\/en\/wp-json\/wp\/v2\/news-events"}],"about":[{"href":"https:\/\/areeya.co.th\/en\/wp-json\/wp\/v2\/types\/news-events"}],"author":[{"embeddable":true,"href":"https:\/\/areeya.co.th\/en\/wp-json\/wp\/v2\/users\/6"}],"version-history":[{"count":0,"href":"https:\/\/areeya.co.th\/en\/wp-json\/wp\/v2\/news-events\/11979\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/areeya.co.th\/en\/wp-json\/wp\/v2\/media\/11974"}],"wp:attachment":[{"href":"https:\/\/areeya.co.th\/en\/wp-json\/wp\/v2\/media?parent=11979"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}